{"id":881,"date":"2023-08-23T12:54:29","date_gmt":"2023-08-23T11:54:29","guid":{"rendered":"https:\/\/logbookdemamanourse.fr\/?p=881"},"modified":"2023-08-24T13:26:30","modified_gmt":"2023-08-24T12:26:30","slug":"astuces-pour-bien-preparer-la-rentree-scolaire","status":"publish","type":"post","link":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/","title":{"rendered":"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"881\" class=\"elementor elementor-881\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-rapcsmy elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"rapcsmy\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ffd739\" data-id=\"5ffd739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db39ed2 elementor-widget elementor-widget-image\" data-id=\"db39ed2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/elementor\/thumbs\/7-astuces-pour-bien-preparer-la-rentree-scolaire-qbdoz5bo4gs1ywkead1ecl0bxgjkd1at1dr4ca46fc.jpg\" title=\"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire\" alt=\"7 astuces pour bien pr\u00e9parer la rentr\u00e9e\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4757c15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4757c15\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f6bd945\" data-id=\"f6bd945\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9b665a elementor-widget elementor-widget-heading\" data-id=\"f9b665a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire\u200b<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d25264 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d25264\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5637e9\" data-id=\"e5637e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41d85a4 elementor-widget elementor-widget-text-editor\" data-id=\"41d85a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>En tant que maman solo, bien pr\u00e9parer la rentr\u00e9e, me permet de g\u00e9rer mon temps, mon \u00e9nergie et mon budget. <\/strong><strong>Voici mes conseils et astuces pour pr\u00e9parer la rentr\u00e9e scolaire et all\u00e9ger mon budget.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4da536 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4da536\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f76d34\" data-id=\"1f76d34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75a2b33 elementor-widget elementor-widget-heading\" data-id=\"75a2b33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><em>Astuce n\u00b01 : <\/em>Les a<\/strong>ides financi\u00e8res<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a0d166 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a0d166\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4bf707\" data-id=\"d4bf707\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-664ca1a elementor-widget elementor-widget-text-editor\" data-id=\"664ca1a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>L\u2019allocation de rentr\u00e9e scolaire<\/strong> (ARS) pour tous les enfants scolaris\u00e9s de 6 \u00e0 18 ans. Le versement a lieu \u00e0 la fin du mois d\u2019ao\u00fbt pr\u00e9c\u00e9dant la rentr\u00e9e scolaire et en une seule fois. D&rsquo;autre par les montants sont consultables sur le site de la CAF rubrique Aides et d\u00e9marches (<strong>clic <a href=\"https:\/\/www.caf.fr\/allocataires\/aides-et-demarches\/droits-et-prestations\/vie-personnelle\/l-allocation-de-rentree-scolaire-ars\" target=\"_blank\" rel=\"noopener\">ici<\/a><\/strong>)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f05d2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f05d2f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b35a411\" data-id=\"b35a411\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea48ea4 elementor-widget elementor-widget-text-editor\" data-id=\"ea48ea4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Les coupons sports<\/strong>\u00a0: CE d\u2019entreprise pour les salari\u00e9s du priv\u00e9, aupr\u00e8s des collectivit\u00e9s locales ou de l\u2019administration pour la fonction publique.<\/li><li><strong>Le passeport loisirs ou Aide au temps libre de la CAF<\/strong>. Il est attribu\u00e9 pour les familles dont les enfants sont \u00e2g\u00e9s de 3 \u00e0 18 ans. Ils doivent \u00eatre inscrits \u00e0 des activit\u00e9s sportives ou culturelles sur l\u2019ann\u00e9e scolaire. Un mail est adress\u00e9 courant du mois d\u2019ao\u00fbt, \u00e0 chaque famille remplissant les conditions pour lui permettre de b\u00e9n\u00e9ficier du Passeport loisirs.<\/li><li><strong>Pass\u2019Sport<\/strong> mis en place par le minist\u00e8re des Sports et des Jeux Olympiques et Paralympiques, pour les jeunes de 6 \u00e0 17 ans r\u00e9volus b\u00e9n\u00e9ficiant de l\u2019allocation de rentr\u00e9e scolaire (ARS), pour les jeunes de 6 \u00e0 20 ans b\u00e9n\u00e9ficiant de l\u2019allocation enfant handicap\u00e9 (AEEH). De plus, le passeport loisirs ou Aide au temps libre de la CAF est cumulable avec le Pass\u2019Sport. Un mail est envoy\u00e9 aux familles courant du mois d\u2019ao\u00fbt.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcb0d1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcb0d1b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2ff2a9\" data-id=\"f2ff2a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17b63ff elementor-widget elementor-widget-text-editor\" data-id=\"17b63ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Les aides aux transports<\/strong>. Se renseigner aupr\u00e8s de sa mairie pour conna\u00eetre les aides financi\u00e8res aux transports. Par exemple pour les d\u00e9partements de Seine et Marne (77), Yvelines (78), Essonne (91) et Val d\u2019Oise (95), il existe la <a href=\"https:\/\/www.iledefrance-mobilites.fr\/titres-et-tarifs\/detail\/la-carte-scolr\" target=\"_blank\" rel=\"noopener\"><strong>carte Scol\u2019R<\/strong><\/a> qui permet aux \u00e9l\u00e8ves de faire un trajet aller-retour quotidien entre le domicile et l\u2019\u00e9cole. Ou encore pour les moins de 11 ans, la r\u00e9gion Ile de France \u00e0 mis en place un forfait imagine R Junior qui permet de voyager en illimit\u00e9 partout en Ile de France. <strong>Tarifs<\/strong> <strong><a href=\"https:\/\/www.iledefrance-mobilites.fr\/titres-et-tarifs\/detail\/forfait-imagine-r-junior\" target=\"_blank\" rel=\"noopener\">ici<\/a><\/strong>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0157e57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0157e57\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dca419\" data-id=\"0dca419\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bd4fe9 elementor-widget elementor-widget-heading\" data-id=\"4bd4fe9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><em>Astuce n\u00b02 : <\/em>La<\/strong> scolarit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba5fee3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba5fee3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa72db8\" data-id=\"fa72db8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2095f13 elementor-widget elementor-widget-text-editor\" data-id=\"2095f13\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prendre tous les \u00e9l\u00e9ments disponibles sur l\u2019\u00e9cole, horaires d\u2019<strong>accueil du matin et du soir<\/strong>, horaires de la <strong>pause m\u00e9ridienne<\/strong> pour les enfants qui ne mangent pas \u00e0 la cantine.<\/p><p>Checklist des documents \u00e0 pr\u00e9parer\u00a0:<\/p><ul><li>Les photos d\u2019identit\u00e9<\/li><li>La copie de l\u2019attestation de l\u2019assurance scolaire<\/li><li>Carte de transport scolaire<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91bec4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91bec4c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e576d23\" data-id=\"e576d23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fba52b3 elementor-widget elementor-widget-heading\" data-id=\"fba52b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><em>Astuce n\u00b03 : <\/em>Les fournitures et le cartable<\/strong><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6c2740 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6c2740\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7e1c70\" data-id=\"d7e1c70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b599bd elementor-widget elementor-widget-text-editor\" data-id=\"2b599bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En premier lieu, se renseigner aupr\u00e8s de sa mairie. En effet certaines mairies participent \u00e0 all\u00e9ger le co\u00fbt des fournitures scolaires pour toutes les familles sans conditions de ressource, ou comme dans ma ville un <strong>kit de rentr\u00e9e<\/strong> pour les coll\u00e9giens sous conditions.<\/p><p>Ensuite, pour faire des \u00e9conomies avant d\u2019aller acheter en magasin, <strong>faire le tri<\/strong> dans les fournitures de l\u2019ann\u00e9e qui vient de s\u2019\u00e9couler. Et\/ou\u00a0 regarder de ce qu\u2019il y a de disponible chez soi. Il reste surement des cahiers, trousses, stylos, crayons de papier, taille crayon, tube de colle\u2026r\u00e9utilisables.<\/p><p>Pour finir, le <strong>cartable<\/strong>, choisir un cartable solide qui durera plusieurs ann\u00e9es.<br \/>Pr\u00e9f\u00e9rer un cartable de <strong>bonne qualit\u00e9 imperm\u00e9able<\/strong>. Le cartable ne doit pas \u00eatre trop grand. La taille standard pour les cartables de CP est 38 cm.<br \/>Pour l\u2019entr\u00e9e en maternelle, m\u00eame si cela nous fait plaisir de voir son enfant faire sa 1<sup>\u00e8re<\/sup> rentr\u00e9e avec son petit sac \u00e0 dos, il n\u2019est pas forc\u00e9ment n\u00e9cessaire. En maternelle la liste de ce qu&rsquo;il faut est redonn\u00e9e \u00e0 la rentr\u00e9e scolaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0005298 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0005298\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c37a65\" data-id=\"8c37a65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae2ccbc elementor-widget elementor-widget-heading\" data-id=\"ae2ccbc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><em>Astuce n\u00b04 : <\/em>L'habillement<\/strong><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d073cee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d073cee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df8be69\" data-id=\"df8be69\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04fe4ed elementor-widget elementor-widget-text-editor\" data-id=\"04fe4ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Apr\u00e8s avoir fait le tri dans l\u2019armoire de ma fille. J\u2019\u00e9tablis une <strong>liste des v\u00eatements et chaussures<\/strong> qui manquent. <br \/>Je fais les <strong>soldes<\/strong> et\/ou profite des <strong>promos de la rentr\u00e9e<\/strong>. J\u2019ai toujours achet\u00e9 au moins une <strong>tenue compl\u00e8te<\/strong>\u00a0 pour <strong>le jour de la rentr\u00e9e<\/strong>. Ensuite, pour les v\u00eatements qui ne vont plus et qui sont encore en tr\u00e8s bon \u00e9tat, les <strong>revendre<\/strong>. Cela permet de <strong>compl\u00e9ter son budget<\/strong>.<\/p><p>Pour certains v\u00eatements comme les <strong>blousons<\/strong>, j\u2019ai toujours pris <strong>plus grands<\/strong>. Les blousons actuels de ma fille ont dur\u00e9 3 ans. Pour le reste des v\u00eatements ils durent 1 \u00e0 2 ans en fonction du d\u00e9veloppement de ma fille et de l\u2019usure qu\u2019elle en fait.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc7d18f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc7d18f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5723f45\" data-id=\"5723f45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19edaf6 elementor-widget elementor-widget-heading\" data-id=\"19edaf6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><em>Astuce n\u00b05 : <\/em>Le p\u00e9riscolaire et le centre de loisirs<em><\/em><\/strong><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e7fcc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e7fcc0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-096af9d\" data-id=\"096af9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e345be2 elementor-widget elementor-widget-text-editor\" data-id=\"e345be2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans la plupart des mairies, les <strong>r\u00e9servations<\/strong> se font <strong>en ligne<\/strong>. <br \/>Aussit\u00f4t que j\u2019ai le m\u00e9mo d\u2019infos du p\u00e9riscolaire pour la rentr\u00e9e suivante, je note les <strong>dates du planning de r\u00e9servation des vacances scolaires<\/strong> dans mon planning annuel. <br \/>Je fais les r\u00e9servations en fonction du planning d\u2019<strong>activit\u00e9s extrascolaire<\/strong> de ma fille et \u00e9galement de mon<strong> emploi du temps professionnel<\/strong>.<\/p><p>Petite astuce : de pr\u00e9f\u00e9rence <strong>faire les r\u00e9servations \u00e0 l\u2019ann\u00e9e<\/strong>. Vis-\u00e0-vis des proc\u00e9dures de r\u00e9servations, il est plus facile d\u2019annuler une r\u00e9servation que de r\u00e9server \u00e0 la derni\u00e8re minute avec le risque de ne pas avoir de place.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec7e784 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec7e784\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3558928\" data-id=\"3558928\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-675da2b elementor-widget elementor-widget-heading\" data-id=\"675da2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><em>Astuce n\u00b06 : <\/em>Les activit\u00e9s extrascolaires<\/strong><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e0f017 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e0f017\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e5854b\" data-id=\"1e5854b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fcd4c9 elementor-widget elementor-widget-text-editor\" data-id=\"0fcd4c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lors des <strong>forums des associations<\/strong> d\u00e9but septembre, organis\u00e9s par de nombreuses communes, il est possible de d\u00e9couvrir les activit\u00e9s et de s\u2019inscrire. <br \/>Profiter des <strong>journ\u00e9es portes ouvertes<\/strong> du mois de septembre pour que l\u2019enfant puisse tester diff\u00e9rentes activit\u00e9s. Vient la question du nombre d\u2019<strong>activit\u00e9s extrascolaires<\/strong>.<\/p><p>Le nombre d\u2019activit\u00e9 extra-scolaire, d\u00e9pend des <strong>d\u00e9sirs de l\u2019enfant<\/strong> et de l\u2019<strong>organisation des parents<\/strong>.<\/p><p>Certaines communes, associations, ou clubs, organisent des <strong>stages (sportifs ou culturels)<\/strong> durant les vacances scolaires. C\u2019est l\u2019occasion de pratiquer une autre activit\u00e9 qui n\u2019est pas pratiqu\u00e9e \u00e0 l\u2019ann\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9564e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9564e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f0f6c8\" data-id=\"5f0f6c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e56f01 elementor-widget elementor-widget-heading\" data-id=\"5e56f01\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><em>Astuce n\u00b07 : <\/em>Les plannings<\/strong><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4157740 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4157740\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b894449\" data-id=\"b894449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5db4135 elementor-widget elementor-widget-text-editor\" data-id=\"5db4135\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Le planning annuel<\/strong>\u00a0: je fais toujours un planning annuel <strong>format A4, <\/strong>que j&rsquo;imprime. Ce qui me permet d\u2019avoir une vision globale sur l\u2019ann\u00e9e scolaire.<\/li><li><strong>Le planning bimensuel<\/strong> : je fais un planning bimensuel (format paysage A4) sur lequel je note les <strong>activit\u00e9s de ma fille<\/strong> (jour et horaires), <strong>les rdvs<\/strong>, les <strong>dates importantes<\/strong> (anniversaires, soldes hiver \u2013 \u00e9t\u00e9, dates d\u00e9claration d\u2019imp\u00f4ts, dates de r\u00e9servation au centre de loisirs). J\u2019imprime un semestre que j\u2019affiche sur les tableaux du <strong>centre de commande familial <\/strong>(endroit o\u00f9 toutes les informations utiles sont regroup\u00e9es).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2c898e elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2c898e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0703db\" data-id=\"b0703db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52fcf95 elementor-widget elementor-widget-spacer\" data-id=\"52fcf95\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8a2fa2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8a2fa2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f69474f\" data-id=\"f69474f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb8713a elementor-widget elementor-widget-text-editor\" data-id=\"fb8713a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En conclusion<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e38b86 elementor-widget elementor-widget-text-editor\" data-id=\"0e38b86\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Finalement, en suivant tout ou partie de mes <strong>astuces<\/strong> , tu pourras t\u2019assurer que la rentr\u00e9e scolaire est un <strong>succ\u00e8s<\/strong> pour ton enfant et toi. Ne pas oublier de <strong>rester positif<\/strong> et <strong>soutenir son enfant<\/strong> tout au long de l\u2019ann\u00e9e scolaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd65992 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd65992\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c78ecf7\" data-id=\"c78ecf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ae8879 elementor-widget elementor-widget-spacer\" data-id=\"5ae8879\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bien pr\u00e9parer la rentr\u00e9e, permet de g\u00e9rer son temps, son \u00e9nergie et son budget.<\/p>\n","protected":false},"author":1,"featured_media":1580,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"gallery","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[15],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire<\/title>\n<meta name=\"description\" content=\"Astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire et \u00e9viter les mauvaises surprises. Ainsi faire de cette rentr\u00e9e un moment plus serein.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire\" \/>\n<meta property=\"og:description\" content=\"Astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire et \u00e9viter les mauvaises surprises. Ainsi faire de cette rentr\u00e9e un moment plus serein.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/logbookdemamanourse\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T11:54:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T12:26:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Logbookdemamanourse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Logbookdemamanourse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/\"},\"author\":{\"name\":\"Logbookdemamanourse\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/#\/schema\/person\/313a04e2f14f809dafbce2aa8f4c9e2f\"},\"headline\":\"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire\",\"datePublished\":\"2023-08-23T11:54:29+00:00\",\"dateModified\":\"2023-08-24T12:26:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/\"},\"wordCount\":1164,\"publisher\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg\",\"articleSection\":[\"Organisation quotidienne\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/\",\"url\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/\",\"name\":\"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire\",\"isPartOf\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg\",\"datePublished\":\"2023-08-23T11:54:29+00:00\",\"dateModified\":\"2023-08-24T12:26:30+00:00\",\"description\":\"Astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire et \u00e9viter les mauvaises surprises. Ainsi faire de cette rentr\u00e9e un moment plus serein.\",\"breadcrumb\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage\",\"url\":\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg\",\"contentUrl\":\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Pr\u00e9parer la rentr\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/logbookdemamanourse.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/#website\",\"url\":\"https:\/\/logbookdemamanourse.fr\/\",\"name\":\"\",\"description\":\"Savoir s&#039;organiser, c&#039;est s&#039;enrichir pour soi et sa famille\",\"publisher\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/#organization\"},\"alternateName\":\"Logbookdemamanourse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/logbookdemamanourse.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/#organization\",\"name\":\"Logbookdemamanourse\",\"alternateName\":\"logbookdemamanourse\",\"url\":\"https:\/\/logbookdemamanourse.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/03\/Logo_autre-couleur-et-plus-grand.png\",\"contentUrl\":\"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/03\/Logo_autre-couleur-et-plus-grand.png\",\"width\":1000,\"height\":1000,\"caption\":\"Logbookdemamanourse\"},\"image\":{\"@id\":\"https:\/\/logbookdemamanourse.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/logbookdemamanourse\",\"https:\/\/www.instagram.com\/logbookdemamanourse\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/#\/schema\/person\/313a04e2f14f809dafbce2aa8f4c9e2f\",\"name\":\"Logbookdemamanourse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/logbookdemamanourse.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/209be5121defceecc0faba2d70cc38f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/209be5121defceecc0faba2d70cc38f2?s=96&d=mm&r=g\",\"caption\":\"Logbookdemamanourse\"},\"sameAs\":[\"https:\/\/logbookdemamanourse.fr\"],\"url\":\"https:\/\/logbookdemamanourse.fr\/index.php\/author\/sandrine-boukgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire","description":"Astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire et \u00e9viter les mauvaises surprises. Ainsi faire de cette rentr\u00e9e un moment plus serein.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/","og_locale":"fr_FR","og_type":"article","og_title":"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire","og_description":"Astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire et \u00e9viter les mauvaises surprises. Ainsi faire de cette rentr\u00e9e un moment plus serein.","og_url":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/","article_publisher":"https:\/\/www.facebook.com\/logbookdemamanourse","article_published_time":"2023-08-23T11:54:29+00:00","article_modified_time":"2023-08-24T12:26:30+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg","type":"image\/jpeg"}],"author":"Logbookdemamanourse","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Logbookdemamanourse","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#article","isPartOf":{"@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/"},"author":{"name":"Logbookdemamanourse","@id":"https:\/\/logbookdemamanourse.fr\/#\/schema\/person\/313a04e2f14f809dafbce2aa8f4c9e2f"},"headline":"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire","datePublished":"2023-08-23T11:54:29+00:00","dateModified":"2023-08-24T12:26:30+00:00","mainEntityOfPage":{"@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/"},"wordCount":1164,"publisher":{"@id":"https:\/\/logbookdemamanourse.fr\/#organization"},"image":{"@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg","articleSection":["Organisation quotidienne"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/","url":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/","name":"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire","isPartOf":{"@id":"https:\/\/logbookdemamanourse.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage"},"image":{"@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg","datePublished":"2023-08-23T11:54:29+00:00","dateModified":"2023-08-24T12:26:30+00:00","description":"Astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire et \u00e9viter les mauvaises surprises. Ainsi faire de cette rentr\u00e9e un moment plus serein.","breadcrumb":{"@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#primaryimage","url":"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg","contentUrl":"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/08\/Image-mise-en-avant-7-astuces-pour-bien-preparer-la-rentree-scolaire-1.jpg","width":1200,"height":630,"caption":"Pr\u00e9parer la rentr\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/logbookdemamanourse.fr\/index.php\/2023\/08\/23\/astuces-pour-bien-preparer-la-rentree-scolaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/logbookdemamanourse.fr\/"},{"@type":"ListItem","position":2,"name":"7 astuces pour bien pr\u00e9parer la rentr\u00e9e scolaire"}]},{"@type":"WebSite","@id":"https:\/\/logbookdemamanourse.fr\/#website","url":"https:\/\/logbookdemamanourse.fr\/","name":"","description":"Savoir s&#039;organiser, c&#039;est s&#039;enrichir pour soi et sa famille","publisher":{"@id":"https:\/\/logbookdemamanourse.fr\/#organization"},"alternateName":"Logbookdemamanourse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/logbookdemamanourse.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/logbookdemamanourse.fr\/#organization","name":"Logbookdemamanourse","alternateName":"logbookdemamanourse","url":"https:\/\/logbookdemamanourse.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/logbookdemamanourse.fr\/#\/schema\/logo\/image\/","url":"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/03\/Logo_autre-couleur-et-plus-grand.png","contentUrl":"https:\/\/logbookdemamanourse.fr\/wp-content\/uploads\/2023\/03\/Logo_autre-couleur-et-plus-grand.png","width":1000,"height":1000,"caption":"Logbookdemamanourse"},"image":{"@id":"https:\/\/logbookdemamanourse.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/logbookdemamanourse","https:\/\/www.instagram.com\/logbookdemamanourse\/"]},{"@type":"Person","@id":"https:\/\/logbookdemamanourse.fr\/#\/schema\/person\/313a04e2f14f809dafbce2aa8f4c9e2f","name":"Logbookdemamanourse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/logbookdemamanourse.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/209be5121defceecc0faba2d70cc38f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/209be5121defceecc0faba2d70cc38f2?s=96&d=mm&r=g","caption":"Logbookdemamanourse"},"sameAs":["https:\/\/logbookdemamanourse.fr"],"url":"https:\/\/logbookdemamanourse.fr\/index.php\/author\/sandrine-boukgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/posts\/881"}],"collection":[{"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/comments?post=881"}],"version-history":[{"count":116,"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/posts\/881\/revisions"}],"predecessor-version":[{"id":1919,"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/posts\/881\/revisions\/1919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/media\/1580"}],"wp:attachment":[{"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/media?parent=881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/categories?post=881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/logbookdemamanourse.fr\/index.php\/wp-json\/wp\/v2\/tags?post=881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}